{"id":14339,"date":"2019-09-10T00:27:20","date_gmt":"2019-09-10T04:27:20","guid":{"rendered":""},"modified":"2019-09-10T00:27:20","modified_gmt":"2019-09-10T04:27:20","slug":"wolfgang-schalk-obsession-frame-up-music","status":"publish","type":"post","link":"https:\/\/www.jazzweek.com\/releases\/2019\/09\/wolfgang-schalk-obsession-frame-up-music\/","title":{"rendered":"Wolfgang Schalk: <i>Obsession<\/i> (Frame Up Music)"},"content":{"rendered":"<p>Wolfgang Schalk: <i>Obsession<\/i> (Frame Up Music)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wolfgang Schalk: Obsession (Frame Up Music)<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[14794,10186,14792],"class_list":["post-14339","post","type-post","status-publish","format-standard","hentry","category-cd","tag-frame-up-music","tag-obsession","tag-wolfgang-schalk"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wolfgang Schalk: Obsession (Frame Up Music) - JazzWeek CD Releases<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jazzweek.com\/releases\/2019\/09\/wolfgang-schalk-obsession-frame-up-music\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wolfgang Schalk: Obsession (Frame Up Music) - JazzWeek CD Releases\" \/>\n<meta property=\"og:description\" content=\"Wolfgang Schalk: Obsession (Frame Up Music)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jazzweek.com\/releases\/2019\/09\/wolfgang-schalk-obsession-frame-up-music\/\" \/>\n<meta property=\"og:site_name\" content=\"JazzWeek CD Releases\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-10T04:27:20+00:00\" \/>\n<meta name=\"author\" content=\"JazzWeek\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"JazzWeek\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/2019\\\/09\\\/wolfgang-schalk-obsession-frame-up-music\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/2019\\\/09\\\/wolfgang-schalk-obsession-frame-up-music\\\/\"},\"author\":{\"name\":\"JazzWeek\",\"@id\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/#\\\/schema\\\/person\\\/720f1acf4bd76d7842e20fc8e4aea820\"},\"headline\":\"Wolfgang Schalk: Obsession (Frame Up Music)\",\"datePublished\":\"2019-09-10T04:27:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/2019\\\/09\\\/wolfgang-schalk-obsession-frame-up-music\\\/\"},\"wordCount\":12,\"commentCount\":0,\"keywords\":[\"Frame Up Music\",\"Obsession\",\"Wolfgang Schalk\"],\"articleSection\":[\"CD Releases\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/2019\\\/09\\\/wolfgang-schalk-obsession-frame-up-music\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/2019\\\/09\\\/wolfgang-schalk-obsession-frame-up-music\\\/\",\"url\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/2019\\\/09\\\/wolfgang-schalk-obsession-frame-up-music\\\/\",\"name\":\"Wolfgang Schalk: Obsession (Frame Up Music) - JazzWeek CD Releases\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/#website\"},\"datePublished\":\"2019-09-10T04:27:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/#\\\/schema\\\/person\\\/720f1acf4bd76d7842e20fc8e4aea820\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/2019\\\/09\\\/wolfgang-schalk-obsession-frame-up-music\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/2019\\\/09\\\/wolfgang-schalk-obsession-frame-up-music\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/2019\\\/09\\\/wolfgang-schalk-obsession-frame-up-music\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wolfgang Schalk: Obsession (Frame Up Music)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/#website\",\"url\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/\",\"name\":\"JazzWeek CD Releases\",\"description\":\"The Weekly Guide to Jazz Radio Airplay\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/#\\\/schema\\\/person\\\/720f1acf4bd76d7842e20fc8e4aea820\",\"name\":\"JazzWeek\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88f4cac56665d0a0da090b3af0bda8fd4b0c11ac2240edb32b2591668a6d46dc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88f4cac56665d0a0da090b3af0bda8fd4b0c11ac2240edb32b2591668a6d46dc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88f4cac56665d0a0da090b3af0bda8fd4b0c11ac2240edb32b2591668a6d46dc?s=96&d=mm&r=g\",\"caption\":\"JazzWeek\"},\"url\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/author\\\/jazzweek\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wolfgang Schalk: Obsession (Frame Up Music) - JazzWeek CD Releases","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jazzweek.com\/releases\/2019\/09\/wolfgang-schalk-obsession-frame-up-music\/","og_locale":"en_US","og_type":"article","og_title":"Wolfgang Schalk: Obsession (Frame Up Music) - JazzWeek CD Releases","og_description":"Wolfgang Schalk: Obsession (Frame Up Music)","og_url":"https:\/\/www.jazzweek.com\/releases\/2019\/09\/wolfgang-schalk-obsession-frame-up-music\/","og_site_name":"JazzWeek CD Releases","article_published_time":"2019-09-10T04:27:20+00:00","author":"JazzWeek","twitter_card":"summary_large_image","twitter_misc":{"Written by":"JazzWeek"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jazzweek.com\/releases\/2019\/09\/wolfgang-schalk-obsession-frame-up-music\/#article","isPartOf":{"@id":"https:\/\/www.jazzweek.com\/releases\/2019\/09\/wolfgang-schalk-obsession-frame-up-music\/"},"author":{"name":"JazzWeek","@id":"https:\/\/www.jazzweek.com\/releases\/#\/schema\/person\/720f1acf4bd76d7842e20fc8e4aea820"},"headline":"Wolfgang Schalk: Obsession (Frame Up Music)","datePublished":"2019-09-10T04:27:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jazzweek.com\/releases\/2019\/09\/wolfgang-schalk-obsession-frame-up-music\/"},"wordCount":12,"commentCount":0,"keywords":["Frame Up Music","Obsession","Wolfgang Schalk"],"articleSection":["CD Releases"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jazzweek.com\/releases\/2019\/09\/wolfgang-schalk-obsession-frame-up-music\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jazzweek.com\/releases\/2019\/09\/wolfgang-schalk-obsession-frame-up-music\/","url":"https:\/\/www.jazzweek.com\/releases\/2019\/09\/wolfgang-schalk-obsession-frame-up-music\/","name":"Wolfgang Schalk: Obsession (Frame Up Music) - JazzWeek CD Releases","isPartOf":{"@id":"https:\/\/www.jazzweek.com\/releases\/#website"},"datePublished":"2019-09-10T04:27:20+00:00","author":{"@id":"https:\/\/www.jazzweek.com\/releases\/#\/schema\/person\/720f1acf4bd76d7842e20fc8e4aea820"},"breadcrumb":{"@id":"https:\/\/www.jazzweek.com\/releases\/2019\/09\/wolfgang-schalk-obsession-frame-up-music\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jazzweek.com\/releases\/2019\/09\/wolfgang-schalk-obsession-frame-up-music\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jazzweek.com\/releases\/2019\/09\/wolfgang-schalk-obsession-frame-up-music\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jazzweek.com\/releases\/"},{"@type":"ListItem","position":2,"name":"Wolfgang Schalk: Obsession (Frame Up Music)"}]},{"@type":"WebSite","@id":"https:\/\/www.jazzweek.com\/releases\/#website","url":"https:\/\/www.jazzweek.com\/releases\/","name":"JazzWeek CD Releases","description":"The Weekly Guide to Jazz Radio Airplay","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jazzweek.com\/releases\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.jazzweek.com\/releases\/#\/schema\/person\/720f1acf4bd76d7842e20fc8e4aea820","name":"JazzWeek","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/88f4cac56665d0a0da090b3af0bda8fd4b0c11ac2240edb32b2591668a6d46dc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/88f4cac56665d0a0da090b3af0bda8fd4b0c11ac2240edb32b2591668a6d46dc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/88f4cac56665d0a0da090b3af0bda8fd4b0c11ac2240edb32b2591668a6d46dc?s=96&d=mm&r=g","caption":"JazzWeek"},"url":"https:\/\/www.jazzweek.com\/releases\/author\/jazzweek\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jazzweek.com\/releases\/wp-json\/wp\/v2\/posts\/14339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jazzweek.com\/releases\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jazzweek.com\/releases\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jazzweek.com\/releases\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jazzweek.com\/releases\/wp-json\/wp\/v2\/comments?post=14339"}],"version-history":[{"count":0,"href":"https:\/\/www.jazzweek.com\/releases\/wp-json\/wp\/v2\/posts\/14339\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jazzweek.com\/releases\/wp-json\/wp\/v2\/media?parent=14339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jazzweek.com\/releases\/wp-json\/wp\/v2\/categories?post=14339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jazzweek.com\/releases\/wp-json\/wp\/v2\/tags?post=14339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}