{"id":9247,"count":1,"description":"","link":"https:\/\/www.jazzweek.com\/releases\/tag\/resonation\/","name":"Resonation","slug":"resonation","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resonation Archives - JazzWeek CD Releases<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jazzweek.com\/releases\/tag\/resonation\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resonation Archives - JazzWeek CD Releases\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jazzweek.com\/releases\/tag\/resonation\/\" \/>\n<meta property=\"og:site_name\" content=\"JazzWeek CD Releases\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/tag\\\/resonation\\\/\",\"url\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/tag\\\/resonation\\\/\",\"name\":\"Resonation Archives - JazzWeek CD Releases\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/tag\\\/resonation\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/tag\\\/resonation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resonation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/#website\",\"url\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/\",\"name\":\"JazzWeek CD Releases\",\"description\":\"The Weekly Guide to Jazz Radio Airplay\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jazzweek.com\\\/releases\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resonation Archives - JazzWeek CD Releases","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jazzweek.com\/releases\/tag\/resonation\/","og_locale":"en_US","og_type":"article","og_title":"Resonation Archives - JazzWeek CD Releases","og_url":"https:\/\/www.jazzweek.com\/releases\/tag\/resonation\/","og_site_name":"JazzWeek CD Releases","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.jazzweek.com\/releases\/tag\/resonation\/","url":"https:\/\/www.jazzweek.com\/releases\/tag\/resonation\/","name":"Resonation Archives - JazzWeek CD Releases","isPartOf":{"@id":"https:\/\/www.jazzweek.com\/releases\/#website"},"breadcrumb":{"@id":"https:\/\/www.jazzweek.com\/releases\/tag\/resonation\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jazzweek.com\/releases\/tag\/resonation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jazzweek.com\/releases\/"},{"@type":"ListItem","position":2,"name":"Resonation"}]},{"@type":"WebSite","@id":"https:\/\/www.jazzweek.com\/releases\/#website","url":"https:\/\/www.jazzweek.com\/releases\/","name":"JazzWeek CD Releases","description":"The Weekly Guide to Jazz Radio Airplay","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jazzweek.com\/releases\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.jazzweek.com\/releases\/wp-json\/wp\/v2\/tags\/9247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jazzweek.com\/releases\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.jazzweek.com\/releases\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.jazzweek.com\/releases\/wp-json\/wp\/v2\/posts?tags=9247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}